{"id":4936,"date":"2019-03-29T16:30:55","date_gmt":"2019-03-29T15:30:55","guid":{"rendered":"https:\/\/novoforno.com\/?page_id=4936\/"},"modified":"2019-03-29T17:14:28","modified_gmt":"2019-03-29T16:14:28","slug":"focaccia-blanca-catering-atm-y-congelados","status":"publish","type":"page","link":"https:\/\/novoforno.com\/es\/focaccia-blanca-catering-atm-y-congelados\/","title":{"rendered":"Focaccia Blanca Catering ATM y Congelados"},"content":{"rendered":"<div class=\"wpb-content-wrapper\">[vc_row css=\u00bb.vc_custom_1550250111260{padding-top: 30px !important;}\u00bb][vc_column 0=\u00bb\u00bb width=\u00bb1\/3&#8243;][vc_single_image image=\u00bb4527&#8243; img_size=\u00bblarge\u00bb alignment=\u00bbcenter\u00bb][\/vc_column][vc_column width=\u00bb2\/3&#8243;][vc_column_text]\n<p style=\"font-size: 14pt;\">La Focaccia Catering Bianca \u00e8 ottenuta da un impasto costituito dalle seguenti materie prime di grande qualit\u00e0: semola di grano duro rimacinata, farina di grano tenero, lecitina di soia, olio extravergine d\u2019oliva, olio di semi di girasole, sale, lievito di birra, acqua, miglioratore. Contiene glutine e soia.<br \/>\nCondimento: pomodorini di collina, olive nere, origano.<br \/>\nLavorata artigianalmente, confezionata in ATM e inserito in un film plastico per alimenti.<\/p>\n<p>&nbsp;<\/p>\n<p style=\"font-size: 14pt;\"><b>DISPONIBILE NEL FORMATO:<\/b><\/p>\n<p>&nbsp;<\/p>\n<ul style=\"font-size: 16pt; line-height: 1.5;\">\n<li><b>Peso:<\/b> 1000g &#8211; <b>Dimensioni:<\/b> 30x40cm<\/li>\n<\/ul>\n<p>&nbsp;<\/p>\n<p style=\"font-size: 14pt;\">Pu\u00f2 essere conservato in un normale refrigeratore domestico da 0\u00b0C a +4\u00b0C o anche surgelato a -20\u00b0C assicurando uno stockaggio di lunga durata fino a 12 mesi.<\/p>\n[\/vc_column_text][\/vc_column][\/vc_row]\n<\/div>","protected":false},"excerpt":{"rendered":"<p>[vc_row css=\u00bb.vc_custom_1550250111260{padding-top: 30px !important;}\u00bb][vc_column 0=\u00bb\u00bb width=\u00bb1\/3&#8243;][vc_single_image image=\u00bb4527&#8243; img_size=\u00bblarge\u00bb alignment=\u00bbcenter\u00bb][\/vc_column][vc_column width=\u00bb2\/3&#8243;][vc_column_text] La Focaccia Catering Bianca \u00e8 ottenuta da un impasto costituito dalle seguenti materie prime di grande qualit\u00e0: semola di grano duro rimacinata, farina di grano tenero, lecitina di soia, olio [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-4936","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Focaccia Blanca Catering ATM y Congelados - Novoforno Altamura<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/novoforno.com\/es\/focaccia-blanca-catering-atm-y-congelados\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Focaccia Blanca Catering ATM y Congelados - Novoforno Altamura\" \/>\n<meta property=\"og:description\" content=\"[vc_row css=\u00bb.vc_custom_1550250111260{padding-top: 30px !important;}\u00bb][vc_column 0=\u00bb\u00bb width=\u00bb1\/3&#8243;][vc_single_image image=\u00bb4527&#8243; img_size=\u00bblarge\u00bb alignment=\u00bbcenter\u00bb][\/vc_column][vc_column width=\u00bb2\/3&#8243;][vc_column_text] La Focaccia Catering Bianca \u00e8 ottenuta da un impasto costituito dalle seguenti materie prime di grande qualit\u00e0: semola di grano duro rimacinata, farina di grano tenero, lecitina di soia, olio [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/novoforno.com\/es\/focaccia-blanca-catering-atm-y-congelados\/\" \/>\n<meta property=\"og:site_name\" content=\"Novoforno Altamura\" \/>\n<meta property=\"article:modified_time\" content=\"2019-03-29T16:14:28+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/novoforno.com\\\/es\\\/focaccia-blanca-catering-atm-y-congelados\\\/\",\"url\":\"https:\\\/\\\/novoforno.com\\\/es\\\/focaccia-blanca-catering-atm-y-congelados\\\/\",\"name\":\"Focaccia Blanca Catering ATM y Congelados - Novoforno Altamura\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/novoforno.com\\\/#website\"},\"datePublished\":\"2019-03-29T15:30:55+00:00\",\"dateModified\":\"2019-03-29T16:14:28+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/novoforno.com\\\/es\\\/focaccia-blanca-catering-atm-y-congelados\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/novoforno.com\\\/es\\\/focaccia-blanca-catering-atm-y-congelados\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/novoforno.com\\\/es\\\/focaccia-blanca-catering-atm-y-congelados\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/novoforno.com\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Focaccia Blanca Catering ATM y Congelados\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/novoforno.com\\\/#website\",\"url\":\"https:\\\/\\\/novoforno.com\\\/\",\"name\":\"Novoforno Altamura\",\"description\":\"&quot;Novoforno Altamura: pane di Altamura DOP, taralli, biscotti, Patatine di pane e specialit\u00e0 da forno surgelate, Basi Pizze, Pinse, Focacce e Panfocaccia dalla tradizione pugliese alla tua tavola \u2014 anche in private label.&quot;\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/novoforno.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Focaccia Blanca Catering ATM y Congelados - Novoforno Altamura","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/novoforno.com\/es\/focaccia-blanca-catering-atm-y-congelados\/","og_locale":"es_ES","og_type":"article","og_title":"Focaccia Blanca Catering ATM y Congelados - Novoforno Altamura","og_description":"[vc_row css=\u00bb.vc_custom_1550250111260{padding-top: 30px !important;}\u00bb][vc_column 0=\u00bb\u00bb width=\u00bb1\/3&#8243;][vc_single_image image=\u00bb4527&#8243; img_size=\u00bblarge\u00bb alignment=\u00bbcenter\u00bb][\/vc_column][vc_column width=\u00bb2\/3&#8243;][vc_column_text] La Focaccia Catering Bianca \u00e8 ottenuta da un impasto costituito dalle seguenti materie prime di grande qualit\u00e0: semola di grano duro rimacinata, farina di grano tenero, lecitina di soia, olio [&hellip;]","og_url":"https:\/\/novoforno.com\/es\/focaccia-blanca-catering-atm-y-congelados\/","og_site_name":"Novoforno Altamura","article_modified_time":"2019-03-29T16:14:28+00:00","twitter_card":"summary_large_image","twitter_misc":{"Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/novoforno.com\/es\/focaccia-blanca-catering-atm-y-congelados\/","url":"https:\/\/novoforno.com\/es\/focaccia-blanca-catering-atm-y-congelados\/","name":"Focaccia Blanca Catering ATM y Congelados - Novoforno Altamura","isPartOf":{"@id":"https:\/\/novoforno.com\/#website"},"datePublished":"2019-03-29T15:30:55+00:00","dateModified":"2019-03-29T16:14:28+00:00","breadcrumb":{"@id":"https:\/\/novoforno.com\/es\/focaccia-blanca-catering-atm-y-congelados\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/novoforno.com\/es\/focaccia-blanca-catering-atm-y-congelados\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/novoforno.com\/es\/focaccia-blanca-catering-atm-y-congelados\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/novoforno.com\/es\/"},{"@type":"ListItem","position":2,"name":"Focaccia Blanca Catering ATM y Congelados"}]},{"@type":"WebSite","@id":"https:\/\/novoforno.com\/#website","url":"https:\/\/novoforno.com\/","name":"Novoforno Altamura","description":"&quot;Novoforno Altamura: pane di Altamura DOP, taralli, biscotti, Patatine di pane e specialit\u00e0 da forno surgelate, Basi Pizze, Pinse, Focacce e Panfocaccia dalla tradizione pugliese alla tua tavola \u2014 anche in private label.&quot;","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/novoforno.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"}]}},"_links":{"self":[{"href":"https:\/\/novoforno.com\/es\/wp-json\/wp\/v2\/pages\/4936","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/novoforno.com\/es\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/novoforno.com\/es\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/novoforno.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/novoforno.com\/es\/wp-json\/wp\/v2\/comments?post=4936"}],"version-history":[{"count":1,"href":"https:\/\/novoforno.com\/es\/wp-json\/wp\/v2\/pages\/4936\/revisions"}],"predecessor-version":[{"id":4937,"href":"https:\/\/novoforno.com\/es\/wp-json\/wp\/v2\/pages\/4936\/revisions\/4937"}],"wp:attachment":[{"href":"https:\/\/novoforno.com\/es\/wp-json\/wp\/v2\/media?parent=4936"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}